{"id":9,"date":"2020-05-18T14:15:25","date_gmt":"2020-05-18T12:15:25","guid":{"rendered":"https:\/\/stage.wikimedia.de\/2019\/?post_type=themen&#038;p=9"},"modified":"2020-07-16T14:36:58","modified_gmt":"2020-07-16T12:36:58","slug":"technische-wuensche","status":"publish","type":"themen","link":"https:\/\/www.wikimedia.de\/2019\/themen\/technische-wuensche\/","title":{"rendered":"Technische W\u00fcnsche"},"content":{"rendered":"<div class=\"block-success-number\">\n\t<div class=\"callout base-green-bg\" style=\"transform: rotate(10deg);\">\n\t  <div class=\"content hand-1\">\n\t  \t<!-- wp:heading {\"level\":3} -->\n<h3>1515 Menschen<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>haben 2019 an der Umfrage zu Technischen W\u00fcnschen teilgenommen.<\/p>\n<!-- \/wp:paragraph -->\t  <\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt \u201eTechnische W\u00fcnsche\u201c entstand 2013 aus einem Impuls der Wikipedia-Freiwilligen mit einer Umfrage von benutzer:raymond: Wo dr\u00fcckt der Schuh am meisten, welche technischen Probleme gibt es in der Wikipedia und ihren Schwesterprojekten? Seit 2015 f\u00fchrt Wikimedia Deutschland die \u201eTechnischen W\u00fcnsche\u201c nach bew\u00e4hrtem Prinzip fort. Wikipedianer*innen sammeln ihre Anliegen, dann wird abgestimmt, welches Problem das dringlichste ist. Das Projekt strahlt in die internationale Community aus, umgesetzte Verbesserungen in der deutschsprachigen Wikipedia werden auch in anderen Wikis \u00fcbernommen. Welcher Wunsch 2019 die Abstimmung gewonnen und was es damit auf sich hat, erkl\u00e4rt Wikimedias Produktmanagerin Technische W\u00fcnsche, Lena Meintrup.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Was hat sich bei den \u201eTechnischen W\u00fcnschen\u201c 2019 getan?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben 2019 den Arbeitsmodus ein bisschen ge\u00e4ndert. Freiwillige k\u00f6nnen nat\u00fcrlich immer noch ihre Anliegen auf einem Wunschparkplatz abstellen und sammeln. Aber vor der Umfrage werden die Probleme jetzt in Themenfelder geb\u00fcndelt, sortiert und m\u00f6glichst zug\u00e4nglich umschrieben. Die Idee dahinter war, dass man ein Problem ja erstmal verstanden haben muss, um sich dazu in der Abstimmung verhalten zu k\u00f6nnen. Wir wollten die \u201eTechnischen W\u00fcnsche\u201c f\u00fcr Freiwillige, die vielleicht noch keine lange Erfahrung und erst ein paar Mal editiert haben, zug\u00e4nglicher machen. Diese Themenfelder haben wir dann in der Umfrage 2019 zur Wahl gestellt. Unser neuer Arbeitsmodus sieht vor, dass wir jedes Jahr eine Umfrage starten und dann zwei Jahre an dem jeweiligen Themenfeld arbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem hat das Team an bereits gew\u00e4hlten W\u00fcnschen gearbeitet, zum Beispiel um das <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Technische_W%C3%BCnsche\/Topw%C3%BCnsche\/Verschieben_von_Dateien_nach_Commons\">Verschieben von Dateien nach Commons<\/a> zu erleichtern oder eine <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Technische_W%C3%BCnsche\/Topw%C3%BCnsche\/Vorschau_von_Einzelnachweisen_im_Artikeltext\">Vorschau von Einzelnachweisen<\/a> im Artikeltext anzuzeigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Welche Bereiche standen zur Abstimmung?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insgesamt waren es 13 Themenschwerpunkte. Dazu z\u00e4hlten \u201eBessere Unterst\u00fctzung von Geo-Informationen\u201c, \u201eInhalte leichter vor Vandalismus sch\u00fctzen\u201c, \u201eFehler bei der Arbeit mit Belegen reduzieren\u201c oder auch \u201eLeichter finden, was ich suche\u201c. Die Abstimmung gewonnen hat mit 298 Stimmen \u201eLeichter mit Vorlagen arbeiten\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Was f\u00fcr technische H\u00fcrden gibt es bei den Vorlagen?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt in der Wikipedia sehr viele verschiedene und spezielle Vorlagen, zum Beispiel gibt es eine Infobox Vorlage f\u00fcr Seiten die sich mit Fu\u00dfballspielern besch\u00e4ftigen, und eine f\u00fcr Fu\u00dfballklubs. . Vielen Freiwilligen f\u00e4llt es deswegen schwer, den \u00dcberblick zu behalten und die passende f\u00fcr ihren Bedarf zu finden. Au\u00dferdem gibt es mehrere verschiedene Wege, Vorlagen auf Seiten einzusetzen und zu bearbeiten: \u00fcber den Visual Editor oder den Wiki-Text-Editor. Besonders im Visual Editor ist die Arbeit mit Vorlagen eine Herausforderung. Und ganz grunds\u00e4tzlich erschwert die aktuelle Vorlagen Syntax die Erstellung und Wartung von Vorlagen.\u00a0 Wir haben in diesen Problembereichen\u00a0 L\u00f6sungsvorschl\u00e4ge als Prototypen entwickelt, zu denen wir jetzt von der Community Feedback einholen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Welche Vorschl\u00e4ge sind das zum Beispiel?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Vorschlag lautete: \u201e<em>Suchfilter f\u00fcr ausgezeichnete Vorlagen\u201c<\/em> \u2013 also das Ausbauen der Suchm\u00f6glichkeiten zum Finden von Vorlagen und die Einf\u00fchrung von ausgezeichneten Vorlagen nach dem Vorbild der<a href=\"https:\/\/de.wikipedia.org\/wiki\/Wikipedia:Bewertungen\"> exzellenten Artikel, informativen Listen und ausgezeichneten Bildern<\/a>. Dann kam durch das Feedback die Erkenntnis\u00a0 dass ausgezeichnete Vorlagen gar nicht so erw\u00fcnscht w\u00e4ren wie zum Beispiel die M\u00f6glichkeit pers\u00f6nliche Favoriten anlegen zu k\u00f6nnen. Wozu positive R\u00fcckmeldungen kamen, waren die Suchfilter. Also Vorlagen besser sichtbar, leichter auffindbar zu machen. An dieser Idee arbeiten wir jetzt weiter.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"731\" src=\"https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte.png\" alt=\"\" class=\"wp-image-89\" srcset=\"https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte.png 512w, https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte-210x300.png 210w, https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte-480x685.png 480w, https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte-360x514.png 360w, https:\/\/www.wikimedia.de\/2019\/wp-content\/uploads\/sites\/2\/2020\/05\/Technische_W\u00fcnsche_Prozess_Themenschwerpunkte-240x343.png 240w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Infografik zum Arbeitsprozess im Projekt Technische W\u00fcnsche: Es wird parallel stets an zwei Themenschwerpunkten gearbeitet, welche von der deutschsprachigen Community per Umfrage festgelegt werden. <br><a href=\"https:\/\/commons.wikimedia.org\/wiki\/User:Erdinc_Ciftci_(WMDE)\">Erdinc Ciftci (WMDE)<\/a>,<a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Technische_W%C3%BCnsche_Prozess_Themenschwerpunkte.png\"> Technische W\u00fcnsche Prozess Themenschwerpunkte<\/a>,<a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/legalcode\"> CC BY-SA 4.0<\/a><\/figcaption><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 FRAGEN AN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>benutzer:raymond<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Warum hast du das Projekt \u201eTechnische W\u00fcnsche\u201c gestartet?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als vor einigen Jahren der Visual Editor eingef\u00fchrt wurde \u2013 im Grunde eine Word-\u00e4hnliche What-you-see-is-what-you-get-Oberfl\u00e4che \u2013 kam aus der Community viel Kritik. Um eine konstruktive Diskussion zu starten, habe ich eine Seite namens \u201eTechnische Wunschliste\u201c aufgesetzt und in die Community gefragt, wo denn in der technischen Entwicklung Schwerpunkte gesetzt werden sollen. Das kam schnell gut an. Wikimedia Deutschland hat mich dann kontaktiert und mir Unterst\u00fctzung beim Sammeln und Priorisieren der W\u00fcnsche&nbsp; angeboten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>L\u00e4sst sich theoretisch alles umsetzen, was die Community vorbringt?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht alles, was die Wikipedianer*innen sich w\u00fcnschen, ist auch realisierbar. Aber es ist schon vieles umgesetzt worden. Wir haben das Projekt sp\u00e4ter auch in der Wikimedia Foundation in San Francisco vorgestellt, die Interesse hatte, es auf eine h\u00f6here Ebene zu bringen. Mittlerweile gibt es die Umfrage zu den \u201eTechnischen W\u00fcnschen\u201c also auch international.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Welche umgesetzten Projekte fandest du hilfreich?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zum Beispiel Vorschau von Einzelnachweisen im Artikeltext, die M\u00f6glichkeit, eine Kategorie auf neue Artikel hin zu beobachten, oder das technisch saubere Verschieben von Dateien nach Wikimdia Commons unter Beibehaltung der Versionsgeschichte und des Benutzernamens \u2013 das waren Verbesserungen, die auch mir pers\u00f6nlich viel in der t\u00e4glichen Arbeit mit Wikipedia&nbsp; bringen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt \u201eTechnische W\u00fcnsche\u201c entstand 2013 aus einem Impuls der Wikipedia-Freiwilligen mit einer Umfrage von benutzer:raymond: Welche Unzufriedenheiten bestehen, welche technischen Probleme gibt es mit den User-Interfaces? Seit 2015 f\u00fchrt WMDE die \u201eTechnischen W\u00fcnsche\u201c nach bew\u00e4hrtem Prinzip fort. Wikipedianer*innen sammeln ihre Anliegen, dann wird abgestimmt, welches Problem das dringlichste ist. Das Projekt strahlt in die internationale Community aus, L\u00f6sungsstrategien werden auch in anderen Wikis \u00fcbernommen. Welcher Wunsch 2019 die Abstimmung gewonnen und was es damit auf sich hat, erkl\u00e4rt Wikimedias Produktmanagerin Laura Meintrup.<\/p>\n","protected":false},"featured_media":201,"template":"","categories":[8],"class_list":["post-9","themen","type-themen","status-publish","has-post-thumbnail","hentry","category-freiwillige"],"acf":[],"lang":"de","translations":{"de":9,"en":354},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/themen\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/themen"}],"about":[{"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/types\/themen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/media\/201"}],"wp:attachment":[{"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wikimedia.de\/2019\/wp-json\/wp\/v2\/categories?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}